{"id":964,"date":"2013-07-05T10:17:49","date_gmt":"2013-07-05T08:17:49","guid":{"rendered":"http:\/\/www.uscolorado.ch\/colo\/?p=964"},"modified":"2013-07-05T10:23:35","modified_gmt":"2013-07-05T08:23:35","slug":"964","status":"publish","type":"post","link":"https:\/\/www.uscolorado.ch\/colo\/964\/","title":{"rendered":"Le Tirage au Sort des groupes 2013-2014 !"},"content":{"rendered":"<p>Voici les \u00e9quipes qui seront oppos\u00e9es \u00e0 notre 5\u00e8me ligue !<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/image.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-962\" alt=\"image\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/image.jpg\" width=\"572\" height=\"611\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/image.jpg 572w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/image-280x300.jpg 280w\" sizes=\"auto, (max-width: 572px) 100vw, 572px\" \/><\/a><\/p>\n<p>Et celles de nos valeureux seniors !<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/image1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-963\" alt=\"image\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/image1.jpg\" width=\"552\" height=\"591\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/image1.jpg 552w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/image1-280x300.jpg 280w\" sizes=\"auto, (max-width: 552px) 100vw, 552px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici les \u00e9quipes qui seront oppos\u00e9es \u00e0 notre 5\u00e8me ligue ! Et celles de nos valeureux seniors !<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-964","post","type-post","status-publish","format-standard","hentry","category-club"],"_links":{"self":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/comments?post=964"}],"version-history":[{"count":2,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/964\/revisions"}],"predecessor-version":[{"id":967,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/964\/revisions\/967"}],"wp:attachment":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/media?parent=964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/categories?post=964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/tags?post=964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}