{"id":2331,"date":"2015-07-31T14:56:11","date_gmt":"2015-07-31T12:56:11","guid":{"rendered":"http:\/\/www.uscolorado.ch\/colo\/?p=2331"},"modified":"2015-07-31T14:56:11","modified_gmt":"2015-07-31T12:56:11","slug":"une-page-se-tourne","status":"publish","type":"post","link":"https:\/\/www.uscolorado.ch\/colo\/une-page-se-tourne\/","title":{"rendered":"Une page se tourne&#8230;"},"content":{"rendered":"<p>Chers amis du Colorado,<\/p>\n<p>Une page s\u2019est tourn\u00e9e cette semaine, avec le retour au Tessin d\u2019un de nos membres les plus embl\u00e9matiques, Mattia.<\/p>\n<p>Apr\u00e8s 9 saisons pass\u00e9es aux Club, il quitte Gen\u00e8ve pour retrouver son canton natal, et le moins que l\u2019on puisse dire c\u2019est qu\u2019il va laisser un grand vide.<\/p>\n<p>Grand artisan de la promotion en 4<sup>\u00e8me<\/sup> ligue lors de sa 1<sup>\u00e8re<\/sup> saison 2006\/2007, il est rapidement devenu incontournable dans notre club, tant pas son niveau de jeu que par sa gentillesse et son \u00e9tat d\u2019esprit irr\u00e9prochable. Ce n\u2019est d\u2019ailleurs pas un hasard s\u2019il a \u00e9t\u00e9 nomm\u00e9 capitaine la majorit\u00e9 des saisons qu\u2019il a jou\u00e9es parmi nous.<\/p>\n<p>Sa simple pr\u00e9sence suffisait \u00e0 motiver toute l\u2019\u00e9quipe, son calme et sa discr\u00e9tion imposaient le respect. Sans parler de son fair-play. En 9 saisons, et positionn\u00e9 comme d\u00e9fenseur, il n\u2019aura subi qu\u2019une dizaine de cartons jaunes, et pas un seul carton rouge.<\/p>\n<p>Son implication dans les activit\u00e9s du club a \u00e9galement \u00e9t\u00e9 extraordinaire. D\u00e8s qu\u2019il fallait organiser une manifestation, un loto, ou quoique ce soit pour son club, il a toujours r\u00e9pondu pr\u00e9sent et s\u2019est chaque fois donn\u00e9 sans compter. Comme sur le terrain en fait.<\/p>\n<p>Et je n\u2019ose m\u00eame pas imaginer le nombre de kilom\u00e8tres parcouru entre Locarno et Gen\u00e8ve pour pouvoir \u00eatre pr\u00e9sent aux matches\u00a0!<\/p>\n<p>Les souvenirs se bousculent lorsque je repense \u00e0 tous ces matches jou\u00e9s ensemble. Les premi\u00e8res images qui me reviennent sont celles de son premier match jou\u00e9 au Bout-du-Monde face \u00e0 Gen\u00e8ve-Ville. Puis son premier but, contre Fribourgeoise, d\u2019une t\u00eate sous la latte sur corner de Jos\u00e9 Garcia. Un geste qui deviendra sa sp\u00e9cialit\u00e9 maison.<\/p>\n<p>D\u00e9fenseur impassable, buteur, passeur\u2026 et chambreur \u00e0 ses heures, nombreux furent les d\u00e9bats avec son \u00ab\u00a0agent\u00a0\u00bb Noam le milaniste face \u00e0 Mattia l\u2019interiste\u00a0!<\/p>\n<p>Lorsqu\u2019une partie de ses co\u00e9quipiers est pass\u00e9e en seniors, il a tenu la baraque tant qu\u2019il pouvait, essayant d\u2019inculquer la philosophie du Colo aux nouveaux jeunes qui arrivaient. Et pour moi une chose \u00e9tait claire, si quelqu\u2019un ne s\u2019entendait pas avec Mattia, il n\u2019avait rien \u00e0 faire l\u00e0.<\/p>\n<p>Puis quand enfin il eut l\u2019\u00e2ge de raison, le retrouver sur la pelouse fut un plaisir immense. Tout comme pour tous ceux qui ne l\u2019avait encore pas c\u00f4toy\u00e9 sur le terrain. Combien de fois, au moment de faire les convocations, j\u2019entendais \u00ab\u00a0il est l\u00e0 Mattia\u00a0?\u00a0Il peut venir\u00a0?\u00bb\u00a0!<\/p>\n<p>Tu vas nous manquer \u00ab\u00a0La Montagna\u00a0\u00bbet ton no17. Alors d\u2019accord tu nous quittes sur un but splendide lors du dernier match \u00e0 Choulex, mais lundi, lorsque les entrainements de la nouvelle saison vont commencer et qu\u2019il faudra \u00e9tablir les contingents, mettre ton nom en rouge \u00e7a va \u00eatre difficile.<\/p>\n<p>Le mot n\u2019est pas trop fort, tu es et restera un exemple pour tous. Ce fut un honneur d\u2019avoir \u00e9t\u00e9 ton co\u00e9quipier et que tu sois devenu mon ami.<\/p>\n<p>Je soumettrai d\u2019ailleurs au vote de la prochaine Assembl\u00e9e du Club, ta nomination comme Membre d\u2019Honneur, une \u00e9vidence\u00a0!<\/p>\n<p>Au nom de tous les membres actuels et pass\u00e9s de l\u2019US Colorado, je te remercie pour tout ce que tu as fait pour notre Colo (merci \u00e9galement \u00e0 ta compagne pour sa patience et sa compr\u00e9hension), et te souhaite tout le meilleur pour ta nouvelle vie tessinoise avec ta belle petite famille\u00a0!<\/p>\n<p>GRAZIE GRANDE MATTIA\u00a0!!!<\/p>\n<p>&nbsp;<\/p>\n<p>P.S. Deux autres joueurs embl\u00e9matiques nous quittent aussi cette saison, Nico et Fabian, je vous pr\u00e9pare aussi un petit mot tr\u00e8s vite\u00a0! Nico, n\u2019oublie pas que Sion champion ce n\u2019est qu\u2019une illusion\u00a0! Et Fabian, j\u2019ai des dossiers\u00a0!<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2335\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m1.jpg\" alt=\"m1\" width=\"604\" height=\"380\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m1.jpg 604w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m1-300x189.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m1-477x300.jpg 477w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m0.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2333\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m0.jpg\" alt=\"m0\" width=\"604\" height=\"402\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m0.jpg 604w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m0-300x200.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m0-451x300.jpg 451w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2341\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m7.jpg\" alt=\"m7\" width=\"604\" height=\"402\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m7.jpg 604w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m7-300x200.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m7-451x300.jpg 451w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2334\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m01.jpg\" alt=\"m01\" width=\"453\" height=\"604\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m01.jpg 453w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m01-225x300.jpg 225w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2340\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m6.jpg\" alt=\"m6\" width=\"525\" height=\"480\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m6.jpg 525w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m6-300x274.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m6-328x300.jpg 328w\" sizes=\"auto, (max-width: 525px) 100vw, 525px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2337\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m3.jpg\" alt=\"m3\" width=\"564\" height=\"960\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m3.jpg 564w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m3-176x300.jpg 176w\" sizes=\"auto, (max-width: 564px) 100vw, 564px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2339\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m5.jpg\" alt=\"m5\" width=\"720\" height=\"540\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m5.jpg 720w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m5-300x225.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m5-400x300.jpg 400w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2342\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m8.jpg\" alt=\"m8\" width=\"396\" height=\"507\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m8.jpg 396w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m8-234x300.jpg 234w\" sizes=\"auto, (max-width: 396px) 100vw, 396px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2338\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m4.jpg\" alt=\"m4\" width=\"960\" height=\"626\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m4.jpg 960w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m4-300x196.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m4-460x300.jpg 460w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2336\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m2.jpg\" alt=\"m2\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m2.jpg 960w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m2-300x225.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m2-400x300.jpg 400w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2344\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m11.jpg\" alt=\"m11\" width=\"698\" height=\"720\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m11.jpg 698w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m11-291x300.jpg 291w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2343\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m9.jpg\" alt=\"m9\" width=\"664\" height=\"960\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m9.jpg 664w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m9-208x300.jpg 208w\" sizes=\"auto, (max-width: 664px) 100vw, 664px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m12.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2345\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m12.jpg\" alt=\"m12\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m12.jpg 960w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m12-300x225.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/m12-400x300.jpg 400w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chers amis du Colorado, Une page s\u2019est tourn\u00e9e cette semaine, avec le retour au Tessin d\u2019un de nos membres les plus embl\u00e9matiques, Mattia. Apr\u00e8s 9 saisons pass\u00e9es aux Club, il quitte Gen\u00e8ve pour retrouver son canton natal, et le moins que l\u2019on puisse dire c\u2019est qu\u2019il va laisser un grand vide. Grand artisan de la [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2331","post","type-post","status-publish","format-standard","hentry","category-club"],"_links":{"self":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/2331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/comments?post=2331"}],"version-history":[{"count":2,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/2331\/revisions"}],"predecessor-version":[{"id":2346,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/2331\/revisions\/2346"}],"wp:attachment":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/media?parent=2331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/categories?post=2331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/tags?post=2331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}