{"id":2037,"date":"2014-11-03T15:14:20","date_gmt":"2014-11-03T14:14:20","guid":{"rendered":"http:\/\/www.uscolorado.ch\/colo\/?p=2037"},"modified":"2014-11-04T10:54:34","modified_gmt":"2014-11-04T09:54:34","slug":"le-point-sur-la-situation-des-equipes-du-colorado","status":"publish","type":"post","link":"https:\/\/www.uscolorado.ch\/colo\/le-point-sur-la-situation-des-equipes-du-colorado\/","title":{"rendered":"Le point sur la situation des \u00e9quipes du Colorado"},"content":{"rendered":"<p>Nos trois \u00e9quipes entament le dernier mois de championnat du 1<sup>er<\/sup> tour de la saison 2014-2015, et nous pouvons constater qu\u2019elles ont pour l\u2019instant des destins tr\u00e8s diff\u00e9rents.<\/p>\n<p>Commen\u00e7ons par les ain\u00e9s, les Seniors 40+, qui progressent petit \u00e0 petit, malgr\u00e9 des probl\u00e8mes d\u2019effectif r\u00e9currents. Lors du dernier match \u00e0 Versoix, nous avons pu observer que l\u2019\u00e9quipe de Coach Alex avait am\u00e9lior\u00e9 son sens tactique, \u00a0se faisant moins pi\u00e9ger par les r\u00e8gles quelque peu diff\u00e9rentes du foot \u00e0 7. Le retour \u00e0 la comp\u00e9tition de nombreux joueurs qui n\u2019avaient plus jou\u00e9 depuis des ann\u00e9es n\u2019est pas simple, surtout au niveau physique o\u00f9 les claquages et contractures sont malheureusement trop fr\u00e9quents. Dommage car les 40+ auraient certainement pu accrocher le bon wagon des 6 premi\u00e8res places, et jouer un 2<sup>\u00e8me<\/sup> tour plus relev\u00e9. Pourtant le plaisir est bien l\u00e0, et cela se voit sur le terrain. Plus que trois matches avant la tr\u00eave, avec 2 adversaires \u00e0 leur port\u00e9e (Champel et Vernier), puis un dernier match \u00e0 Meinier, leader invaincu du groupe\u00a0!<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-40.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2036\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-40.jpg\" alt=\"prog 40\" width=\"594\" height=\"190\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-40.jpg 594w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-40-300x95.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-40-500x159.jpg 500w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/class-40.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2033\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/class-40.jpg\" alt=\"class 40\" width=\"600\" height=\"361\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/class-40.jpg 600w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/class-40-300x180.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/class-40-500x300.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Les Seniors 30+ sont eux en bien mauvaise posture. Un d\u00e9but de championnat catastrophique, et un encha\u00eenement de blessures incroyable, au point que vendredi pass\u00e9, on pouvait compter pas moins de 10 joueurs absents. Si on rajoute \u00e0 cela une certaine maladresse devant le but (pour ne pas dire une maladresse certaine), les r\u00e9sultats n\u00e9gatifs se sont accumul\u00e9s, malgr\u00e9 un fond de jeu pas si mauvais et de la qualit\u00e9 parmi les joueurs. Le dernier match face au Stade Fran\u00e7ais fut un parfait exemple de ce 1<sup>er<\/sup> tour jusqu\u2019ici. Bonne entame de match, de belles actions, une d\u00e9fense qui tient bien, et 25 minutes \u00e0 faire jeu \u00e9gal avec l\u2019adversaire. S\u2019en suit une \u00e9norme occasion rat\u00e9e, puis sur le contre, un p\u00e9nalty g\u00e9n\u00e9reux conc\u00e9d\u00e9. Palabres avec l\u2019arbitre, la moiti\u00e9 de l\u2019\u00e9quipe qui sort de son match, et le 2-0 encaiss\u00e9 une minute plus tard\u2026 Il est donc grand temps de se remettre tous en question, et de faire preuve d\u2019une grinta d\u00e9cupl\u00e9e\u00a0! On sait tous que l\u2019\u00e9quipe a largement les moyens de remonter au classement, mais il faut se les donner ces moyens. Et \u00e7a passe \u00e9videmment par plus d\u2019assiduit\u00e9 aux entrainements, et de retrouver la confiance pour \u00e9viter les nombreuses fautes techniques qui se paient cash. Coach JF pense ne plus \u00eatre en mesure de motiver le groupe, il a donc d\u00e9cid\u00e9 de laisser les rennes de l\u2019\u00e9quipe \u00e0 Nico et Pipo pour la fin de ce 1<sup>er<\/sup> tour. Des d\u00e9cisions seront prises pendant la tr\u00eave, mais d\u2019ici l\u00e0 il reste 3 matches \u00e0 jouer pour prouver notre vraie valeur\u00a0! Ce sera d\u2019abord nos amis de l\u2019Etoile-Espagnole, qui se situent 4 points devant nous, puis l\u2019Union Sud-Am\u00e9ricaine (5 points), et pour finirle FC Choulex. Rien ne sera facile, mais une chose est s\u00fbre, les 30+ donneront tout\u00a0!<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-30.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2035\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-30.jpg\" alt=\"prog 30\" width=\"597\" height=\"191\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-30.jpg 597w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-30-300x95.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-30-500x159.jpg 500w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Class-30.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2032\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Class-30.jpg\" alt=\"Class 30\" width=\"596\" height=\"358\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Class-30.jpg 596w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Class-30-300x180.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Class-30-500x300.jpg 500w\" sizes=\"auto, (max-width: 596px) 100vw, 596px\" \/><\/a>Terminons notre passage en revue par la grande satisfaction de la saison, notre \u00e9quipe de Jeunes de Coach Jos\u00e9, qui occupe le podium du classement depuis le d\u00e9but du 1<sup>er<\/sup> tour. Avec un gros effectif, des joueurs pr\u00e9sents et concern\u00e9s aux entrainements et aux matches, une ambiance d\u2019\u00e9quipe qui se ressent imm\u00e9diatement, et un turn-over intelligent pour que tous ceux qui se donnent aient du temps de jeu, notre 5<sup>\u00e8me<\/sup> ligue fait plaisir \u00e0 voir. Et les r\u00e9sultats sont l\u00e0. Malgr\u00e9 une d\u00e9faite face au leader et deux nuls, l\u2019\u00e9quipe ne baisse jamais les bras et a faim\u00a0! La preuve ce dimanche avec les 9 buts inscrits face \u00e0 Rhexia-Vessy. Si la mont\u00e9e est le but avou\u00e9, Jos\u00e9 est bien pr\u00e9sent pour calmer les ardeurs de chacun et garder la t\u00eate froide. Le chemin est encore long, avec 14 matches \u00e0 jouer\u2026 Le prochain vaudra d\u2019ailleurs son pesant d\u2019or, face \u00e0 l\u2019Etoile-Espagnole qui se situe 1 point devant au classement. Le calme et la confiance en son jeu seront des param\u00e8tres d\u00e9terminants pour aller chercher la victoire\u00a0! Ensuite il restera un dernier match face au Stade Fran\u00e7ais, pour essayer de bien finir ce beau 1<sup>er<\/sup> tour. Autre point positif, l\u2019obtention du sponsoring de nouveaux maillots rouge (domicile) et blanc (ext\u00e9rieur) tr\u00e8s \u00e9l\u00e9gants\u00a0! Beaux maillots, beau jeu, belle \u00e9quipe, faut que \u00e7a dure\u00a0!<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-51.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2038\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-51.jpg\" alt=\"prog 5\" width=\"594\" height=\"141\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-51.jpg 594w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-51-300x71.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-51-500x118.jpg 500w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Class-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2031\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Class-5.jpg\" alt=\"Class 5\" width=\"600\" height=\"389\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Class-5.jpg 600w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Class-5-300x194.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Class-5-462x300.jpg 462w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Un dernier mot pour remercier toutes les supportrices et supporters qui sont venus encourager les 3 \u00e9quipes jusqu\u2019\u00e0 maintenant. On esp\u00e8re que le froid de novembre ne les emp\u00eachera pas de venir pour ces derniers matches cruciaux\u00a0! Leur pr\u00e9sence est appr\u00e9ci\u00e9e et motivante\u00a0! Sans oublier Jenn et ses splendides photos des matches des Jeunes\u00a0!<\/p>\n<p>Et \u00e9galement un grand merci \u00e0 nos 3 coaches Jos\u00e9, Alex et JF, qui donnent beaucoup de leur temps et de leur \u00e9nergie pour mettre en conditions plus de 50 joueurs de foot, donc plus de 50 personnalit\u00e9s et caract\u00e8res diff\u00e9rents\u00a0! Un bel effort qui, je l\u2019esp\u00e8re, sera r\u00e9compens\u00e9 par de nombreuses victoires et de bons moments sur et au bord des terrains du canton\u00a0!<\/p>\n<p>ALLEZ COLOOOOOOOOOOOOOOOOOOOOOOOOOOO\u00a0!!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos trois \u00e9quipes entament le dernier mois de championnat du 1er tour de la saison 2014-2015, et nous pouvons constater qu\u2019elles ont pour l\u2019instant des destins tr\u00e8s diff\u00e9rents. Commen\u00e7ons par les ain\u00e9s, les Seniors 40+, qui progressent petit \u00e0 petit, malgr\u00e9 des probl\u00e8mes d\u2019effectif r\u00e9currents. Lors du dernier match \u00e0 Versoix, nous avons pu observer [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2037","post","type-post","status-publish","format-standard","hentry","category-club"],"_links":{"self":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/2037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/comments?post=2037"}],"version-history":[{"count":3,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/2037\/revisions"}],"predecessor-version":[{"id":2189,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/2037\/revisions\/2189"}],"wp:attachment":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/media?parent=2037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/categories?post=2037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/tags?post=2037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}