{"id":1889,"date":"2014-09-29T12:12:20","date_gmt":"2014-09-29T10:12:20","guid":{"rendered":"http:\/\/www.uscolorado.ch\/colo\/?p=1889"},"modified":"2014-09-29T12:15:30","modified_gmt":"2014-09-29T10:15:30","slug":"une-seule-victoire-pour-les-equipes-du-colorado-ce-weekend","status":"publish","type":"post","link":"https:\/\/www.uscolorado.ch\/colo\/une-seule-victoire-pour-les-equipes-du-colorado-ce-weekend\/","title":{"rendered":"Une seule victoire pour les \u00e9quipes du Colorado ce weekend&#8230;"},"content":{"rendered":"<p>Alors que l\u2019on esp\u00e9rait c\u00e9l\u00e9brer un tripl\u00e9 de victoires, seul les Seniors 30+ ont apport\u00e9 3 points au club ce weekend.<\/p>\n<p>Les seniors 40+ \u00e9taient les premiers \u00e0 entrer en lice jeudi soir \u00e0 Vernier, face au leader invaincu Avanchet-Sport. D\u00e8s l\u2019appel de l\u2019arbitre notre coach Alex nous dit de se m\u00e9fier de cet \u00e9nergum\u00e8ne bien connu pour son ex\u00e9crable attitude.<\/p>\n<p>Cela se v\u00e9rifia d\u00e8s le d\u00e9but du match, lorsque Jobo ouvrait la marque sur corner et voyait son but annul\u00e9 pour une faute inexistante. Avanchet en profitait pour marquer 2 fois, sur 2 grosses erreurs d\u00e9fensives, et malgr\u00e9 quelques beaux mouvements coloradiens, c\u2019est notre gardien Nikko qui effectuait de magnifiques parades pour \u00e9viter que l\u2019addition soit plus sal\u00e9e \u00e0 la pause. La maladresse des attaquants adverses faisant le reste.<\/p>\n<p>Apr\u00e8s la pause, le Colo r\u00e9agissait et dominait mieux son sujet. Suite \u00e0 une double occasion de Jobo contr\u00e9e par le gardien, Jacco suivait bien et r\u00e9duisait la marque d\u2019un plat du pied plac\u00e9 dans le but vide.<\/p>\n<p>Revigor\u00e9s par ce but, le Colo jetait toutes ses forces dans la bataille, et Nikko officiait merveilleusement bien comme dernier rempart, d\u00e9goutant les attaquants jaune et bleu.<\/p>\n<p>A quelques minutes du terme, Cisco centrait pour Ciro, qui effectuait une magnifique demi-vol\u00e9e sous la transversale pour obtenir une \u00e9galisation m\u00e9rit\u00e9e\u00a0! Mais encore une fois l\u2019arbitre inventait un hors-jeu qui achevait de d\u00e9gouter les rouges du Colo.<\/p>\n<p>Une d\u00e9faite bien dommage, surtout que l\u2019on se demande encore pourquoi ce type arbitre toujours,\u00a0tellement il montrait de m\u00e9pris et n&rsquo;avait visiblement aucune envie d\u2019\u00eatre l\u00e0. A se demander quel plaisir il prend \u00e0 arbitrer \u00e0 part d&rsquo;abuser de son petit pouvoir&#8230;<\/p>\n<p>Mais bref, restant calmes et pragmatiques, les Seniors 40+ attendront encore pour obtenir leur 2<sup>\u00e8me<\/sup> succ\u00e8s de la saison\u00a0! Peut-\u00eatre vendredi au Bout-du-Monde face \u00e0 St-Paul\u00a0? A v\u00e9rifier\u00a0!<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-402.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1886\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-402.jpg\" alt=\"res 40\" width=\"594\" height=\"356\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-402.jpg 594w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-402-300x179.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-402-500x300.jpg 500w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-40b.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1887\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-40b.jpg\" alt=\"res 40b\" width=\"604\" height=\"369\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-40b.jpg 604w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-40b-300x183.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-40b-491x300.jpg 491w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/a><\/p>\n<p>Les Seniors 30+ enchainaient le vendredi soir \u00e0 Varemb\u00e9, toujours \u00e0 la recherche d\u2019un premier succ\u00e8s cette saison. Malgr\u00e9 une entame de match compliqu\u00e9e et un but conc\u00e9d\u00e9 d\u2019entr\u00e9e, ils ont montr\u00e9 de belles qualit\u00e9 et, enfin, une efficacit\u00e9 dans le dernier geste, m\u00eame si l\u2019on peut toujours faire mieux\u00a0!<\/p>\n<p>Juste avant la pause, men\u00e9s 1-0, ils parvenaient \u00e0 \u00e9galiser par leur capitaine Serge, bien servi par Nico G, puis \u00e0 prendre l\u2019avantage au meilleur moment, par Malamine\u00a0!<\/p>\n<p>2-1 \u00e0 la mi-temps, il s\u2019agissait d\u2019\u00eatre vigilant pendant la 2<sup>\u00e8me<\/sup> p\u00e9riode. Et Malamine encore \u00e9tait l\u00e0 pour inscrire le 3-1 d\u00e9finitif, qui apporte 3 points tr\u00e8s pr\u00e9cieux \u00e0 une \u00e9quipe qui prend forme\u00a0!<\/p>\n<p>Les arriv\u00e9es de Manu et Agustin font un grand bien, en attendant celle d\u2019Haydar d\u00e8s cette semaine\u00a0! Encore quelques r\u00e9glages et on est en droit d\u2019attendre d\u2019autres belles performances\u00a0! Bravo \u00e0 tous et rendez-vous vendredi au Bout-du-Monde pour confirmer\u00a0!<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-303.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1885\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-303.jpg\" alt=\"res 30\" width=\"594\" height=\"590\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-303.jpg 594w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-303-150x150.jpg 150w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-303-300x297.jpg 300w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-303-302x300.jpg 302w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/a><\/p>\n<p>Dimanche matin, par un magnifique soleil mais malgr\u00e9 cela sur le synth\u00e9tique du Bout-du-Monde, les Jeunes recevaient Famalicao, 4 jours apr\u00e8s leur match de Coupe.<\/p>\n<p>Apr\u00e8s une premi\u00e8re mi-temps \u00e9quilibr\u00e9e sold\u00e9e par un match nul 1-1, les rouges se sont fait pi\u00e9ger par le jeu toujours aussi st\u00e9r\u00e9otyp\u00e9 de leurs adversaires. Boum devant et advienne que pourra\u2026<\/p>\n<p>Quelques erreurs de placement et de marquages, un peu de fatigue, et une certaine nervosit\u00e9 auront d\u00e9cid\u00e9 du d\u00e9roulement de ce match.<\/p>\n<p>Contre le cours du jeu Famalic\u00e3o prenait les devants en inscrivant le 2-1. Mais le Colo r\u00e9agissait imm\u00e9diatement en \u00e9galisant \u00e0 2 partout.<\/p>\n<p>S\u2019en suivi \u00e9trangement un trou noir de 10 minutes o\u00f9 les Jeunes encaissaient 2 buts sur des longues balles, et Famalic\u00e3o, incapable de construire une action mais tr\u00e8s volontaire, n\u2019en demandait pas tant.<\/p>\n<p>L\u2019US poussait jusqu\u2019au bout, parfois de mani\u00e8re brouillonne et pr\u00e9cipit\u00e9e, et r\u00e9ussissait \u00e0 r\u00e9duire le score \u00e0 4-3, malheureusement trop tard\u2026<\/p>\n<p>On peut consid\u00e9rer ce match comme un \u00ab\u00a0accident\u00a0\u00bb, mais \u00e9galement comme une piqure de rappel\u00a0: aucun match ne sera gagn\u00e9 d\u2019avance, et il faut rester soud\u00e9 en toutes circonstances. Lorsque l\u2019on est frustr\u00e9 par une d\u00e9cision arbitrale ou une maladresse d\u2019un co\u00e9quipier, il faut utiliser cette rage positivement et tirer l\u2019\u00e9quipe vers le haut plut\u00f4t que s\u2019\u00e9nerver et chercher des responsables.<\/p>\n<p>Car chacun est responsable de son match, et tous les joueurs se doivent d\u2019\u00eatre ensemble, dans la victoire comme dans la d\u00e9faite\u00a0!<\/p>\n<p>Et gare au guerrier bless\u00e9, sa r\u00e9action n\u2019en sera que plus terrible\u00a0! Rendez-vous dimanche prochain \u00e0 Vessy pour voir la r\u00e9action de l\u2019\u00e9quipe\u00a0!<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-56.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1884\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-56.jpg\" alt=\"res 5\" width=\"598\" height=\"623\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-56.jpg 598w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res-56-287x300.jpg 287w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1883\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog.jpg\" alt=\"prog\" width=\"462\" height=\"290\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog.jpg 462w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-300x188.jpg 300w\" sizes=\"auto, (max-width: 462px) 100vw, 462px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que l\u2019on esp\u00e9rait c\u00e9l\u00e9brer un tripl\u00e9 de victoires, seul les Seniors 30+ ont apport\u00e9 3 points au club ce weekend. Les seniors 40+ \u00e9taient les premiers \u00e0 entrer en lice jeudi soir \u00e0 Vernier, face au leader invaincu Avanchet-Sport. D\u00e8s l\u2019appel de l\u2019arbitre notre coach Alex nous dit de se m\u00e9fier de cet \u00e9nergum\u00e8ne [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1889","post","type-post","status-publish","format-standard","hentry","category-club"],"_links":{"self":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/comments?post=1889"}],"version-history":[{"count":4,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1889\/revisions"}],"predecessor-version":[{"id":1893,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1889\/revisions\/1893"}],"wp:attachment":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/media?parent=1889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/categories?post=1889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/tags?post=1889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}