{"id":1218,"date":"2014-03-13T13:26:41","date_gmt":"2014-03-13T12:26:41","guid":{"rendered":"http:\/\/www.uscolorado.ch\/colo\/?p=1218"},"modified":"2014-03-14T00:24:25","modified_gmt":"2014-03-13T23:24:25","slug":"cest-reparti-pour-les-seniors","status":"publish","type":"post","link":"https:\/\/www.uscolorado.ch\/colo\/cest-reparti-pour-les-seniors\/","title":{"rendered":"C&rsquo;est reparti pour les seniors !"},"content":{"rendered":"<p>Au tour de seniors du Colo de reprendre la comp\u00e9tition, avec un 1<sup>er<\/sup> match ce vendredi \u00e0 20h15 \u00e0 Vessy, face au FC Versoix\u00a0!<\/p>\n<p>Si l\u2019assiduit\u00e9 n\u2019a pas vraiment \u00e9t\u00e9 au rendez-vous lors des entra\u00eenements en salle et les premiers entra\u00eenements ext\u00e9rieurs, on compte sur la motivation de l\u2019\u00e9quipe pour faire bonne figure d\u00e8s l\u2019entame de ce 2<sup>\u00e8me<\/sup> tour.<\/p>\n<p>Confront\u00e9s au d\u00e9part de Seba et la malheureuse blessure de Xav, les seniors peuvent n\u00e9anmoins compter sur les arriv\u00e9es d\u2019Elia et Kyuta dans le contingent. Et esp\u00e9rer qu\u2019un maximum de joueurs restera valide le plus longtemps possible !<\/p>\n<p>Apr\u00e8s une phase d\u2019adaptation afin de connaitre le groupe, notre Coach JF est fin pr\u00eat pour tenter de tirer le meilleur de chacun\u00a0!<\/p>\n<p>On compte \u00e9galement sur la bonne ambiance qui r\u00e8gne dans l\u2019\u00e9quipe pour rester soud\u00e9s en toutes circonstances, et pour f\u00eater dignement les bonnes performances\u00a0!<\/p>\n<p>Amiti\u00e9, Fraternit\u00e9, PERSEVERANCE\u00a0!!!<\/p>\n<p>A vendredi pour nos chers supporters, et Allez Colooooooooooo\u00a0!!!<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-sen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1219\" alt=\"prog sen\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-sen.jpg\" width=\"529\" height=\"555\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-sen.jpg 529w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/prog-sen-285x300.jpg 285w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au tour de seniors du Colo de reprendre la comp\u00e9tition, avec un 1er match ce vendredi \u00e0 20h15 \u00e0 Vessy, face au FC Versoix\u00a0! Si l\u2019assiduit\u00e9 n\u2019a pas vraiment \u00e9t\u00e9 au rendez-vous lors des entra\u00eenements en salle et les premiers entra\u00eenements ext\u00e9rieurs, on compte sur la motivation de l\u2019\u00e9quipe pour faire bonne figure d\u00e8s l\u2019entame [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1218","post","type-post","status-publish","format-standard","hentry","category-seniors-news"],"_links":{"self":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/comments?post=1218"}],"version-history":[{"count":3,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1218\/revisions"}],"predecessor-version":[{"id":1223,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1218\/revisions\/1223"}],"wp:attachment":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/media?parent=1218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/categories?post=1218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/tags?post=1218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}