{"id":1116,"date":"2014-01-22T17:19:57","date_gmt":"2014-01-22T16:19:57","guid":{"rendered":"http:\/\/www.uscolorado.ch\/colo\/?p=1116"},"modified":"2014-01-22T17:19:57","modified_gmt":"2014-01-22T16:19:57","slug":"grazie-noam","status":"publish","type":"post","link":"https:\/\/www.uscolorado.ch\/colo\/grazie-noam\/","title":{"rendered":"GRAZIE NOAM !"},"content":{"rendered":"<p>Chers Membres et Amis du Colorado,<\/p>\n<p>Une nouvelle page de l\u2019Histoire de notre Club se tourne, avec le d\u00e9part d\u2019un membre qui aura inscrit de plusieurs mani\u00e8res son nom dans les annales de l\u2019Union Sportive Colorado.<\/p>\n<p>A notre plus grand regret \u00e0 tous, NOAM quitte Gen\u00e8ve pour retrouver son Tessin.<\/p>\n<p>Nous l\u2019avions accueilli il y a plus de 8 ans maintenant, et son parcours parmi nous fut jalonn\u00e9 de moments m\u00e9morables.<\/p>\n<p>Il est rare de pouvoir compter sur des membres aussi d\u00e9vou\u00e9s \u00e0 leur club, et tous ceux qui l\u2019ont c\u00f4toy\u00e9 mesurent leur chance.<\/p>\n<p>En tant que joueur, il a jou\u00e9 \u00e0 presque tous les postes. Si son r\u00f4le de pr\u00e9dilection \u00e9tait attaquant tendance renard des surfaces (avec une jolie capacit\u00e9 \u00e0 distiller des passes d\u00e9cisives), il aura bri\u00e8vement embrass\u00e9 la carri\u00e8re de lat\u00e9ral notamment, ainsi que de gardien de but (le fameux Dida 16\/9).<\/p>\n<p>Il prit ensuite le r\u00f4le de coach et d\u2019entra\u00eeneur, avec des collaborations plus ou moins fructueuses, mais toujours avec son esprit de vainqueur et son sens tactique aff\u00fbt\u00e9.<\/p>\n<p>Parfois trop aff\u00fbt\u00e9 pour certains joueurs un peu plus lents pour comprendre.<\/p>\n<p>Totalement impliqu\u00e9 pour son Colo, il a aussi \u0153uvr\u00e9 en tant qu\u2019agent recruteur, et gr\u00e2ce \u00e0 lui nous avons pu connaitre de superbes joueurs, autant sportivement qu\u2019humainement.<\/p>\n<p>Finalement, il a accompli de nombreuses t\u00e2ches au sein de notre comit\u00e9, derni\u00e8rement en tant que Grand Argentier, et quitte le club juste \u00e0 temps avant qu\u2019on ne l\u2019\u00e9lise pr\u00e9sident !<\/p>\n<p>D\u2019un point de vue personnel, je ne peux que lui adresser un \u00e9norme MERCI pour tout ce qu\u2019il a fait pour le Colo ! Et \u00e9galement un grand BRAVO pour ses performances mythiques !<\/p>\n<p>Toujours disponible (sauf en cas de cours de cornemuse), toujours pr\u00eat pour discuter (surtout autour d\u2019une bonne bi\u00e8re) et toujours impliqu\u00e9, il n\u2019y en a pas beaucoup comme lui !<\/p>\n<p>TU VAS NOUS MANQUER PORCO DIO, DIO PORCO !<\/p>\n<p>Evidemment que tous les membres actuels et anciens lui souhaitent tout le meilleur pour la suite, avec sa jolie petite famille ! Et on esp\u00e8re le revoir tr\u00e8s bient\u00f4t, ici ou chez lui !!<\/p>\n<p>Rendez-vous demain JEUDI SOIR en salle pour son JUBIL\u00c9 et pour trinquer \u00e0 sa sant\u00e9 !<\/p>\n<p>Ciao e Grazie Nono !<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Grazie-Noam.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1115\" alt=\"Grazie Noam\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Grazie-Noam.jpg\" width=\"451\" height=\"623\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Grazie-Noam.jpg 451w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/Grazie-Noam-217x300.jpg 217w\" sizes=\"auto, (max-width: 451px) 100vw, 451px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chers Membres et Amis du Colorado, Une nouvelle page de l\u2019Histoire de notre Club se tourne, avec le d\u00e9part d\u2019un membre qui aura inscrit de plusieurs mani\u00e8res son nom dans les annales de l\u2019Union Sportive Colorado. A notre plus grand regret \u00e0 tous, NOAM quitte Gen\u00e8ve pour retrouver son Tessin. Nous l\u2019avions accueilli il y [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1116","post","type-post","status-publish","format-standard","hentry","category-club"],"_links":{"self":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/comments?post=1116"}],"version-history":[{"count":2,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1116\/revisions"}],"predecessor-version":[{"id":1118,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1116\/revisions\/1118"}],"wp:attachment":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/media?parent=1116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/categories?post=1116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/tags?post=1116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}