{"id":1111,"date":"2014-01-06T14:46:51","date_gmt":"2014-01-06T13:46:51","guid":{"rendered":"http:\/\/www.uscolorado.ch\/colo\/?p=1111"},"modified":"2014-01-06T14:46:51","modified_gmt":"2014-01-06T13:46:51","slug":"bonne-annee-2014","status":"publish","type":"post","link":"https:\/\/www.uscolorado.ch\/colo\/bonne-annee-2014\/","title":{"rendered":"BONNE ANNEE 2014 !"},"content":{"rendered":"<p>Le comit\u00e9 du l&rsquo;US COLORADO souhaite une merveilleuse ann\u00e9e \u00e0 tous ses membres et ses supporters, ainsi qu&rsquo;\u00e0 leurs familles !<\/p>\n<p>Merci \u00e0 tous pour votre engagement en 2013 pour repr\u00e9senter les couleurs du Club, et on se r\u00e9jouit tous de nos futurs exploits en 2014 !!<\/p>\n<p>Avec toujours les m\u00eames mots d&rsquo;ordre :<\/p>\n<p>FAIR-PLAY, BEAU JEU et 3\u00e8me MI-TEMPS !<\/p>\n<p>Allez Colooooooooooooooooooooooooooooooooooooooooo !!!<br \/>\n<a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/brazil-2014-1024x566.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-1112\" alt=\"brazil-2014-1024x566\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/brazil-2014-1024x566.jpg\" width=\"614\" height=\"340\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/brazil-2014-1024x566.jpg 1024w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/brazil-2014-1024x566-300x165.jpg 300w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le comit\u00e9 du l&rsquo;US COLORADO souhaite une merveilleuse ann\u00e9e \u00e0 tous ses membres et ses supporters, ainsi qu&rsquo;\u00e0 leurs familles ! Merci \u00e0 tous pour votre engagement en 2013 pour repr\u00e9senter les couleurs du Club, et on se r\u00e9jouit tous de nos futurs exploits en 2014 !! Avec toujours les m\u00eames mots d&rsquo;ordre : FAIR-PLAY, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1111","post","type-post","status-publish","format-standard","hentry","category-club"],"_links":{"self":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/comments?post=1111"}],"version-history":[{"count":1,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1111\/revisions"}],"predecessor-version":[{"id":1113,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1111\/revisions\/1113"}],"wp:attachment":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/media?parent=1111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/categories?post=1111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/tags?post=1111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}