{"id":1094,"date":"2013-10-10T11:16:32","date_gmt":"2013-10-10T09:16:32","guid":{"rendered":"http:\/\/www.uscolorado.ch\/colo\/?p=1094"},"modified":"2013-10-10T11:16:32","modified_gmt":"2013-10-10T09:16:32","slug":"3eme-prix-du-fair-play-pour-les-jeunes","status":"publish","type":"post","link":"https:\/\/www.uscolorado.ch\/colo\/3eme-prix-du-fair-play-pour-les-jeunes\/","title":{"rendered":"3\u00e8me prix du Fair Play pour les jeunes !"},"content":{"rendered":"<p>Et oui, le Fair Play \u00e7a paie ! Avec leur 3\u00e8me place pour la saison 2012-2013, notre \u00e9quipe de 5\u00e8me ligue remporte un bon de Frs. 500.- !!<\/p>\n<p>Quand on pense au carton rouge de Leandro pour insultes lors du dernier match du 1er tour, et celui de Eran pour la m\u00eame chose lors dernier match du 2\u00e8me tour, la 1ere place n&rsquo;\u00e9tait pas loin, dommage !<\/p>\n<p>Mais BRAVO \u00e0 tous, et merci aux coaches !<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/fair-play.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1093\" alt=\"fair play\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/fair-play.jpg\" width=\"612\" height=\"816\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/fair-play.jpg 612w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/fair-play-225x300.jpg 225w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Et oui, le Fair Play \u00e7a paie ! Avec leur 3\u00e8me place pour la saison 2012-2013, notre \u00e9quipe de 5\u00e8me ligue remporte un bon de Frs. 500.- !! Quand on pense au carton rouge de Leandro pour insultes lors du dernier match du 1er tour, et celui de Eran pour la m\u00eame chose lors dernier [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[11,18],"tags":[],"class_list":["post-1094","post","type-post","status-publish","format-standard","hentry","category-5eme-ligue-news","category-club"],"_links":{"self":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/comments?post=1094"}],"version-history":[{"count":1,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1094\/revisions"}],"predecessor-version":[{"id":1095,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1094\/revisions\/1095"}],"wp:attachment":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/media?parent=1094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/categories?post=1094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/tags?post=1094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}