{"id":1053,"date":"2013-09-23T12:52:02","date_gmt":"2013-09-23T10:52:02","guid":{"rendered":"http:\/\/www.uscolorado.ch\/colo\/?p=1053"},"modified":"2013-09-23T16:45:36","modified_gmt":"2013-09-23T14:45:36","slug":"les-seniors-sont-remontes-au-score-les-jeunes-sont-remontes-contre-larbitre","status":"publish","type":"post","link":"https:\/\/www.uscolorado.ch\/colo\/les-seniors-sont-remontes-au-score-les-jeunes-sont-remontes-contre-larbitre\/","title":{"rendered":"Les seniors sont remont\u00e9s au score, les jeunes sont remont\u00e9s contre l\u2019arbitre\u2026."},"content":{"rendered":"<p>Week-end on\u00e9sien pour les \u00e9quipes du Colo, avec les seniors qui recevaient le FC Onex vendredi soir, et les jeunes qui accueillaient Gala\u00efca-Onex dimanche matin.<\/p>\n<p>Revigor\u00e9s par leur victoire en coupe du lundi face \u00e0 Azzurri (buts de Jobo et Serge), la vieille garde coloradienne avait \u00e0 c\u0153ur d\u2019inverser la tendance face \u00e0 une \u00e9quipe d\u2019Onex qui les avait battus 2 fois la saison pass\u00e9e (2-3 et 1-0).<\/p>\n<p>Dispos\u00e9s une nouvelle fois en 3-5-2, mais orphelins de leur nouveau coach JF (gripp\u00e9), les rouges et noirs s\u2019attendaient \u00e0 une r\u00e9action d\u2019Onex, auteurs d\u2019un d\u00e9but de saison catastrophique.<\/p>\n<p>L\u2019entame de match fut compliqu\u00e9e, c&rsquo;est un euph\u00e9misme.\u00a0Nos adversaires \u00e9taient bien plus vifs et pr\u00e9sents dans les duels que ce Colo apathique des premi\u00e8res minutes.<\/p>\n<p>Lents, pas tr\u00e8s concentr\u00e9s, l\u2019US se mettait en danger toute seule, sans qu\u2019Onex soit r\u00e9ellement efficace. Pourtant, sur leur premi\u00e8re r\u00e9elle occasion, Onex ouvrait la marque contre le cours du jeu.<\/p>\n<p>Encore une fois, il fallait que le Colo soit dans l\u2019adversit\u00e9 pour enfin voir une r\u00e9action. C\u2019est donc apr\u00e8s 20 minutes de jeu tr\u00e8s moyennes que les seniors d\u00e9cid\u00e8rent de prendre les choses en main.<\/p>\n<p>Les vagues d\u2019attaques et les corners se succ\u00e9d\u00e8rent, et leur gardien retardait l\u2019\u00e9ch\u00e9ance. Finalement, sur un coup franc jou\u00e9 rapidement par Fred, Serge frappait au but et le ballon contr\u00e9 par le gardien parvenait \u00e0 Jobo qui n\u2019avait plus qu\u2019\u00e0 le pousser au fond.<\/p>\n<p>On se dit qu\u2019enfin le Colo allait passer l\u2019\u00e9paule et imposer sa loi. Que nenni ! A peine 2 minutes apr\u00e8s l\u2019\u00e9galisation, Onex reprenait l\u2019avantage sur leur 2\u00e8me occasion !<\/p>\n<p>Men\u00e9s 2-1 \u00e0 la pause, les seniors pouvaient s\u2019en vouloir, mais gardaient bien en t\u00eate qu\u2019ils avaient domin\u00e9 leurs adversaires, et qu\u2019\u00e0 force de pers\u00e9v\u00e9rance \u00e7a allait finir par passer.<\/p>\n<p>La seconde p\u00e9riode fut quasiment un monologue coloradien. De nombreuses occasions, du mouvement, et un adversaire qui se fatiguait petit \u00e0 petit face aux assauts des rouges.<\/p>\n<p>Pipo au coaching introduisait des joueurs frais, Onex reculait et r\u00e9sistait tant bien que mal.<\/p>\n<p>L\u2019\u00e9galisation tomba comme un fruit mur. Sur une nouvelle belle ouverture en profondeur pour Jobo, celui-ci arrivait seul face au gardien et d\u00e9calait Nico G. qui allait marquer dans le but vide. Mais un d\u00e9fenseur tentait d\u2019intercepter et propulsa le cuir dans ses propres filets,\u00a02-2 !<\/p>\n<p>Enfin lanc\u00e9s, le Colo \u00e9touffait Onex, et \u00e0\u00a0la suite d\u2019une jolie succession de passes dans l\u2019axe du milieu de terrain, Nikko lance Xav qui part affronter seul le gardien. Petit plat du pied plein de maitrise au ras du poteau,\u00a03-2, l\u2019avantage \u00e9tait pris !<\/p>\n<p>Il fallait maintenant valider d\u00e9finitivement la victoire en inscrivant le but du break. Sur une action totalement identique au but du 3-2, Jobo offrait le 4-2 \u00e0 Nico G., mais l\u2019arbitre annulait le but pour un hors-jeu imaginaire.<\/p>\n<p>Le Colo ne tremblait pourtant pas dans ces derni\u00e8res minutes, et l\u2019estocade arriva \u00e0 5 minutes du terme. Gros pressing de Nico G. sur l\u2019axe de la d\u00e9fense, le gardien on\u00e9sien qui sort de sa surface et tente de d\u00e9gager le ballon, r\u00e9cup\u00e9ration de Jobo \u00e0 35 m\u00e8tres et frappe directe dans le but vide !<\/p>\n<p>4-2 score final, avec une tr\u00e8s belle attitude au niveau du jeu et du mental. Il y a \u00e9videmment encore beaucoup de points perfectibles, notamment au niveau de la couverture d\u00e9fensive (l\u00e9g\u00e8rement statique sur les 2 buts encaiss\u00e9s, et surtout au niveau du r\u00e9alisme offensif, avec d\u2019ENORMES occasions manqu\u00e9es en 1\u00e8re p\u00e9riode. Mais il y de beaux motifs de satisfaction quant au jeu produit.<\/p>\n<p>On sait bien que la tactique du 3-5-2 nous permet de nous cr\u00e9er beaucoup d\u2019occasions, surtout lorsque l\u2019on alterne jeu sur les c\u00f4t\u00e9s et jeu axial. Mais on sait aussi que le danger est plus important en phase d\u00e9fensive, notamment sur les ballons dans le dos lors des contre-attaques.<\/p>\n<p>Un grand bravo \u00e0 toute l\u2019\u00e9quipe pour cette belle performance, suivie d\u2019une buvette encore une fois remport\u00e9e haut la main ! Et merci \u00e9videment aux supporters pr\u00e9sents !!<\/p>\n<p>Rdv vendredi prochain pour d\u00e9fier ADPG, invaincu jusqu\u2019ici !<\/p>\n<p>L\u2019\u00e9quipe de vendredi :<br \/>\nSantos \u2013 Rod Fabian Fred \u2013 Mattia Xav Cisco Malamine Tiago \u2013 Serge Jobo \u2013 Nikko Nico G. Seba Zoltan<\/p>\n<p>Prochain match : VENDREDI 27.09.2013 \u00e0 20h00 au Bout-du-Monde : ADPG \u2013 COLO<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/sen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1060\" alt=\"sen\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/sen.jpg\" width=\"547\" height=\"566\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/sen.jpg 547w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/sen-289x300.jpg 289w\" sizes=\"auto, (max-width: 547px) 100vw, 547px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/resSen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1059\" alt=\"resSen\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/resSen.jpg\" width=\"630\" height=\"594\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/resSen.jpg 630w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/resSen-300x282.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/a><\/p>\n<p>****************************************************************************************************************<\/p>\n<p>Les jeunes accueillaient le Gala\u00efca-Onex (un bon derby pour nos galiciens on\u00e9siens du Colo) dimanche matin.<\/p>\n<p>Une entame de championnat compliqu\u00e9e pour notre 5\u00e8me ligue, avec des premiers matches jou\u00e9s \u00e0 11 ou 12 (et avec des seniors pour faire le nombre), puis depuis la semaine pass\u00e9e, avec un nouvel effectif qui doit encore apprendre \u00e0 se connaitre et jouer ensemble.<\/p>\n<p>Pourtant, depuis le d\u00e9but de la saison, et malgr\u00e9 les d\u00e9faites parfois lourdes, on avait remarqu\u00e9 un bel \u00e9tat d\u2019esprit, avec une envie de bien faire toujours pr\u00e9sente. Ce fut encore le cas face au co-leader hier matin.<\/p>\n<p>Bien en place d\u00e9fensivement, avec un Pablo auteur de superbes parades, le Colo posa de nombreuses difficult\u00e9s \u00e0 Galaica-Onex.<\/p>\n<p>Bien que dominateurs, se cr\u00e9ant plus d\u2019occasions de buts et en ayant plus souvent la possession de balle, nos adversaires n\u2019y arrivaient pas. Et sur quelques contre-attaques, le Colo aurait pu les surprendre.<\/p>\n<p>Cette belle r\u00e9sistance mena le Colo avec un score nul et vierge \u00e0 la pause.<\/p>\n<p>Apr\u00e8s le th\u00e9, Galaica tenta d\u2019acc\u00e9l\u00e9rer, mais \u00e7a ne passait toujours pas. Un petit quart d\u2019heure de jeu pass\u00e9, l\u2019arbitre allait faire basculer le match. Sur une faute hors de la surface, il indiquait le point de penalty.<\/p>\n<p>1-0 pour nos adversaires. Pas compl\u00e9tement illogique au vu de la physionomie du match, mais rageant au vu des circonstances.<\/p>\n<p>Le Colo essayait de r\u00e9agir, mais l\u2019arbitre allait encore faire des siennes. Alors qu\u2019un joueur adverse effectuait un tacle les deux pieds en avant sur un d\u00e9fenseur coloradien, qui \u00e9vitait de justesse le choc, il ne sifflait rien et laissait l\u2019action se poursuivre. Dans la confusion, un attaquant centrait fort devant le but et le ballon \u00e9tait d\u00e9vi\u00e9 par malchance dans nos propres filets par un d\u00e9fenseur.<\/p>\n<p>Le score ne bougera plus, et le Colo tentera de garder son calme malgr\u00e9 la calamiteuse performance d\u2019un arbitre qu\u2019on connait bien pour sa mauvaise foi depuis longtemps.<\/p>\n<p>Cela fait malheureusement partie du jeu, et il faudra faire avec car ce n\u2019est ni la premi\u00e8re ni la derni\u00e8re fois qu\u2019on devra faire face \u00e0 ce genre de chose.<\/p>\n<p>On gardera n\u00e9anmoins en t\u00eate les points positifs de ce match, \u00e0 savoir une assise d\u00e9fensive qui commence \u00e0 \u00eatre l\u00e0, notamment par un bon pressing et une grinta de tous les instants.<\/p>\n<p>Il reste bien s\u00fbr beaucoup de boulot, afin d\u2019am\u00e9liorer les transmissions de balles et la cr\u00e9ation du jeu, mais les jeunes sont sur la bonne voie !<\/p>\n<p>Bravo \u00e0 tous pour vos efforts, et vivement le prochain match, avec une rencontre le vendredi soir \u00e0 Plan-les-Ouates contre quelques ex-coloradiens !<\/p>\n<p>L\u2019\u00e9quipe de dimanche :<br \/>\nPablo \u2013 Jos\u00e9 Riccardo Jon Juanjo \u2013 Philippe Mathias Jeton Artan \u2013 Nicola Durim \u2013 Camilo Eran<\/p>\n<p>Prochain match : VENDREDI 27.09.2013 \u00e0 20h00 aux Cherpines : Plan-Les-Ouates 3 &#8211; COLO<\/p>\n<p><a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/52.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1057\" alt=\"5\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/52.jpg\" width=\"580\" height=\"396\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/52.jpg 580w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/52-300x204.jpg 300w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/a> <a href=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1058\" alt=\"res5\" src=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res5.jpg\" width=\"628\" height=\"500\" srcset=\"https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res5.jpg 628w, https:\/\/www.uscolorado.ch\/colo\/wp-content\/uploads\/res5-300x238.jpg 300w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Week-end on\u00e9sien pour les \u00e9quipes du Colo, avec les seniors qui recevaient le FC Onex vendredi soir, et les jeunes qui accueillaient Gala\u00efca-Onex dimanche matin. Revigor\u00e9s par leur victoire en coupe du lundi face \u00e0 Azzurri (buts de Jobo et Serge), la vieille garde coloradienne avait \u00e0 c\u0153ur d\u2019inverser la tendance face \u00e0 une \u00e9quipe [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1053","post","type-post","status-publish","format-standard","hentry","category-club"],"_links":{"self":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/comments?post=1053"}],"version-history":[{"count":6,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1053\/revisions"}],"predecessor-version":[{"id":1065,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/posts\/1053\/revisions\/1065"}],"wp:attachment":[{"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/media?parent=1053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/categories?post=1053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uscolorado.ch\/colo\/wp-json\/wp\/v2\/tags?post=1053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}